{"id":7194,"date":"2024-03-17T12:51:18","date_gmt":"2024-03-17T11:51:18","guid":{"rendered":"https:\/\/galiancogasa.net\/tienda\/producto\/comedero-perros-tolva-10l-m-cp-242046\/"},"modified":"2026-07-09T11:36:22","modified_gmt":"2026-07-09T09:36:22","slug":"comedero-perros-tolva-10l-m-cp-242046","status":"publish","type":"product","link":"https:\/\/galiancogasa.net\/tienda\/producto\/comedero-perros-tolva-10l-m-cp-242046\/","title":{"rendered":"COMEDERO PERROS TOLVA 10L M CP 24*20*46"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":20562,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[174],"product_tag":[],"class_list":["post-7194","product","type-product","status-publish","has-post-thumbnail","familia_producto-432","product_cat-comederos-y-bebederos-accesorios-perros","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>COMEDERO PERROS TOLVA 10L M CP 24*20*46 - Galian Cogasa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galiancogasa.net\/tienda\/producto\/comedero-perros-tolva-10l-m-cp-242046\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMEDERO PERROS TOLVA 10L M CP 24*20*46\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galiancogasa.net\/tienda\/producto\/comedero-perros-tolva-10l-m-cp-242046\/\" \/>\n<meta property=\"og:site_name\" content=\"Galian Cogasa\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T09:36:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galiancogasa.net\/tienda\/wp-content\/uploads\/2024\/03\/9760509.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/producto\\\/comedero-perros-tolva-10l-m-cp-242046\\\/\",\"url\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/producto\\\/comedero-perros-tolva-10l-m-cp-242046\\\/\",\"name\":\"COMEDERO PERROS TOLVA 10L M CP 24*20*46 - Galian Cogasa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/producto\\\/comedero-perros-tolva-10l-m-cp-242046\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/producto\\\/comedero-perros-tolva-10l-m-cp-242046\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/9760509.png\",\"datePublished\":\"2024-03-17T11:51:18+00:00\",\"dateModified\":\"2026-07-09T09:36:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/producto\\\/comedero-perros-tolva-10l-m-cp-242046\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/producto\\\/comedero-perros-tolva-10l-m-cp-242046\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/producto\\\/comedero-perros-tolva-10l-m-cp-242046\\\/#primaryimage\",\"url\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/9760509.png\",\"contentUrl\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/9760509.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/producto\\\/comedero-perros-tolva-10l-m-cp-242046\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COMEDERO PERROS TOLVA 10L M CP 24*20*46\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/#website\",\"url\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/\",\"name\":\"Galian Cogasa\",\"description\":\"Tienda Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/#organization\",\"name\":\"Galian Cogasa SL\",\"url\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-galian-v2.png\",\"contentUrl\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-galian-v2.png\",\"width\":6156,\"height\":2296,\"caption\":\"Galian Cogasa SL\"},\"image\":{\"@id\":\"https:\\\/\\\/galiancogasa.net\\\/tienda\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"COMEDERO PERROS TOLVA 10L M CP 24*20*46 - Galian Cogasa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galiancogasa.net\/tienda\/producto\/comedero-perros-tolva-10l-m-cp-242046\/","og_locale":"es_ES","og_type":"article","og_title":"COMEDERO PERROS TOLVA 10L M CP 24*20*46","og_url":"https:\/\/galiancogasa.net\/tienda\/producto\/comedero-perros-tolva-10l-m-cp-242046\/","og_site_name":"Galian Cogasa","article_modified_time":"2026-07-09T09:36:22+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/galiancogasa.net\/tienda\/wp-content\/uploads\/2024\/03\/9760509.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galiancogasa.net\/tienda\/producto\/comedero-perros-tolva-10l-m-cp-242046\/","url":"https:\/\/galiancogasa.net\/tienda\/producto\/comedero-perros-tolva-10l-m-cp-242046\/","name":"COMEDERO PERROS TOLVA 10L M CP 24*20*46 - Galian Cogasa","isPartOf":{"@id":"https:\/\/galiancogasa.net\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/galiancogasa.net\/tienda\/producto\/comedero-perros-tolva-10l-m-cp-242046\/#primaryimage"},"image":{"@id":"https:\/\/galiancogasa.net\/tienda\/producto\/comedero-perros-tolva-10l-m-cp-242046\/#primaryimage"},"thumbnailUrl":"https:\/\/galiancogasa.net\/tienda\/wp-content\/uploads\/2024\/03\/9760509.png","datePublished":"2024-03-17T11:51:18+00:00","dateModified":"2026-07-09T09:36:22+00:00","breadcrumb":{"@id":"https:\/\/galiancogasa.net\/tienda\/producto\/comedero-perros-tolva-10l-m-cp-242046\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galiancogasa.net\/tienda\/producto\/comedero-perros-tolva-10l-m-cp-242046\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/galiancogasa.net\/tienda\/producto\/comedero-perros-tolva-10l-m-cp-242046\/#primaryimage","url":"https:\/\/galiancogasa.net\/tienda\/wp-content\/uploads\/2024\/03\/9760509.png","contentUrl":"https:\/\/galiancogasa.net\/tienda\/wp-content\/uploads\/2024\/03\/9760509.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/galiancogasa.net\/tienda\/producto\/comedero-perros-tolva-10l-m-cp-242046\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galiancogasa.net\/tienda\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/galiancogasa.net\/tienda\/tienda\/"},{"@type":"ListItem","position":3,"name":"COMEDERO PERROS TOLVA 10L M CP 24*20*46"}]},{"@type":"WebSite","@id":"https:\/\/galiancogasa.net\/tienda\/#website","url":"https:\/\/galiancogasa.net\/tienda\/","name":"Galian Cogasa","description":"Tienda Online","publisher":{"@id":"https:\/\/galiancogasa.net\/tienda\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galiancogasa.net\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/galiancogasa.net\/tienda\/#organization","name":"Galian Cogasa SL","url":"https:\/\/galiancogasa.net\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/galiancogasa.net\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/galiancogasa.net\/tienda\/wp-content\/uploads\/2024\/01\/logo-galian-v2.png","contentUrl":"https:\/\/galiancogasa.net\/tienda\/wp-content\/uploads\/2024\/01\/logo-galian-v2.png","width":6156,"height":2296,"caption":"Galian Cogasa SL"},"image":{"@id":"https:\/\/galiancogasa.net\/tienda\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/galiancogasa.net\/tienda\/wp-json\/wp\/v2\/product\/7194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galiancogasa.net\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galiancogasa.net\/tienda\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galiancogasa.net\/tienda\/wp-json\/wp\/v2\/media\/20562"}],"wp:attachment":[{"href":"https:\/\/galiancogasa.net\/tienda\/wp-json\/wp\/v2\/media?parent=7194"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galiancogasa.net\/tienda\/wp-json\/wp\/v2\/product_brand?post=7194"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galiancogasa.net\/tienda\/wp-json\/wp\/v2\/product_cat?post=7194"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galiancogasa.net\/tienda\/wp-json\/wp\/v2\/product_tag?post=7194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}